{"id":3434,"date":"2022-10-26T16:00:40","date_gmt":"2022-10-26T14:00:40","guid":{"rendered":"https:\/\/www.avressieux.com\/mairie\/?page_id=3434"},"modified":"2022-10-26T16:00:53","modified_gmt":"2022-10-26T14:00:53","slug":"le-correspondant-defense","status":"publish","type":"page","link":"https:\/\/www.avressieux.com\/mairie\/le-correspondant-defense\/","title":{"rendered":"Le Correspondant D\u00e9fense"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb specialty=\u00a0\u00bbon\u00a0\u00bb background_color_2=\u00a0\u00bbrgba(0,0,0,0.08)\u00a0\u00bb padding_top_1=\u00a0\u00bb20px\u00a0\u00bb padding_top_bottom_link_1=\u00a0\u00bbfalse\u00a0\u00bb padding_left_right_link_1=\u00a0\u00bbfalse\u00a0\u00bb padding_1_tablet=\u00a0\u00bb\u00a0\u00bb padding_1_phone=\u00a0\u00bb|20px||20px|false|false\u00a0\u00bb padding_1_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb inner_width=\u00a0\u00bb100%\u00a0\u00bb inner_max_width=\u00a0\u00bb100%\u00a0\u00bb inner_module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb20px||||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb3_4&Prime; specialty_columns=\u00a0\u00bb3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_row_inner _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb90%\u00a0\u00bb width_tablet=\u00a0\u00bb\u00a0\u00bb width_phone=\u00a0\u00bb\u00a0\u00bb width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_padding=\u00a0\u00bb3px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner saved_specialty_column_type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbOpen Sans|||||on|||\u00a0\u00bb text_text_color=\u00a0\u00bb#02726d\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.avressieux.com\/mairie\/wp-content\/uploads\/2020\/08\/puce1.png\" alt=\"puce\" class=\"wp-image-1266 alignleft size-full\" width=\"30\" height=\"30\" \/>le correspondant d\u00e9fense<\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: 109px; top: 0.200001px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb90%\u00a0\u00bb width_tablet=\u00a0\u00bb\u00a0\u00bb width_phone=\u00a0\u00bb\u00a0\u00bb width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb-22px|||||\u00a0\u00bb custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner saved_specialty_column_type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.avressieux.com\/mairie\/wp-content\/uploads\/2021\/11\/CORDEF-MNL.png\u00a0\u00bb alt=\u00a0\u00bbMarche dans la for\u00eat de Vallin en 2015, entente et amiti\u00e9, avressieux, vie associative, associations\u00a0\u00bb title_text=\u00a0\u00bbCORDEF MNL\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div class=\"elementor-element elementor-element-f220fa3 elementor-drop-cap-yes elementor-drop-cap-view-default elementor-widget elementor-widget-text-editor\" data-id=\"f220fa3\" data-element_type=\"widget\" data-settings=\"{&quot;drop_cap&quot;:&quot;yes&quot;}\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p><span style=\"color: #850a27;\"><strong><\/strong><\/span><\/p>\n<p><span style=\"color: #850a27;\"><strong>Le Correspondant D\u00e9fense est l\u2019interlocuteur privil\u00e9gi\u00e9 des citoyens sur les questions de D\u00e9fense au sein de la commune.<\/strong><\/span> Cr\u00e9\u00e9e en 2001, par le minist\u00e8re d\u00e9l\u00e9gu\u00e9 aux Anciens combattants, la fonction de correspondant d\u00e9fense a vocation \u00e0 d\u00e9velopper le lien arm\u00e9e-nation et promouvoir l\u2019esprit de d\u00e9fense. Le r\u00f4le du correspondant d\u00e9fense est essentiel pour associer pleinement tous les citoyens aux questions de d\u00e9fense.<\/p>\n<p>Le correspondant D\u00e9fense est d\u00e9sign\u00e9 parmi les membres du conseil municipal. Il est l\u2019interlocuteur privil\u00e9gi\u00e9 des autorit\u00e9s civiles et militaires dans la commune pour ce qui concerne les questions de D\u00e9fense et les relations arm\u00e9e-Nation. Il relaie les informations aupr\u00e8s du conseil municipal et des habitants de la commune en les orientant vers les relais professionnels pouvant les renseigner sur les carri\u00e8res militaires, le volontariat et la r\u00e9serve militaire.<\/p>\n<p>Le correspondant D\u00e9fense s\u2019appuie sur un double r\u00e9seau \u00e0 l\u2019\u00e9chelle du territoire. La d\u00e9l\u00e9gation \u00e0 l\u2019information et \u00e0 la communication de la D\u00e9fense (DICoD) organise ce maillage au niveau national. Localement, le correspondant D\u00e9fense s\u2019appuie sur deux relais compl\u00e9mentaires : le d\u00e9l\u00e9gu\u00e9 militaire d\u00e9partemental de la Dordogne (DMD 24) et le r\u00e9f\u00e9rent \u00ab correspondant D\u00e9fense \u00bb de l\u2019Union-IHEDN (Institut des hautes \u00e9tudes de la D\u00e9fense nationale).<\/p>\n<p>La mission du correspondant D\u00e9fense s\u2019organise autour de 3 axes :<\/p>\n<ul>\n<li>Information sur la D\u00e9fense;<\/li>\n<li>parcours citoyen ;<\/li>\n<li>solidarit\u00e9 et m\u00e9moire.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-e5b07f3 elementor-widget elementor-widget-heading\" data-id=\"e5b07f3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h3 class=\"elementor-heading-title elementor-size-default\"><\/h3>\n<h3 class=\"elementor-heading-title elementor-size-default\">1) INFORMATION SUR LA D\u00c9FENSE<\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-1e4c567 elementor-widget elementor-widget-text-editor\" data-id=\"1e4c567\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p><span style=\"color: #850a27;\"><strong>a) Sites d\u2019information sur la d\u00e9fense :<\/strong><\/span><\/p>\n<p>Minist\u00e8re des arm\u00e9es :<br \/><span style=\"color: #850a27;\"><a style=\"color: #850a27;\" href=\"https:\/\/www.defense.gouv.fr\" target=\"_blank\" rel=\"noopener\">www.defense.gouv.fr<\/a><\/span><\/p>\n<p>Actualit\u00e9s de la D\u00e9fense :<br \/><span style=\"color: #850a27;\"><a style=\"color: #850a27;\" href=\"https:\/\/www.defense.gouv.fr\/actualites\/articles\" target=\"_blank\" rel=\"noopener\">defense.gouv.fr\/actualites\/articles<\/a><\/span><\/p>\n<p>Actualit\u00e9s des op\u00e9rations :<br \/><a href=\"https:\/\/www.defense.gouv.fr\/operations\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #850a27;\">defense.gouv.fr\/operations<\/span><\/a><\/p>\n<p><span style=\"color: #850a27;\"><strong>b) Volontariat dans les arm\u00e9es<\/strong><\/span><\/p>\n<p>Le volontariat dans les arm\u00e9es permet aux jeunes Fran\u00e7ais(es) de s\u2019initier aux m\u00e9tiers des armes et de la d\u00e9fense. Le volontaire s\u2019engage pour une dur\u00e9e d\u20191 an renouvelable. Il peut servir dans une unit\u00e9 de l\u2019arm\u00e9e de Terre, de l\u2019Air, de la Marine nationale, de la Gendarmerie nationale ou du Service de sant\u00e9 des arm\u00e9es. Le volontaire per\u00e7oit une solde mensuelle (r\u00e9mun\u00e9ration) et prestations en nature. Il peut avancer en grade, sous conditions. Il peut \u00eatre mis fin au contrat de fa\u00e7on anticip\u00e9e. <span style=\"color: #850a27;\"><a style=\"color: #850a27;\" href=\"https:\/\/www.service-public.fr\/particuliers\/vosdroits\/F1292\" target=\"_blank\" rel=\"noopener\">https:\/\/www.service-public.fr\/particuliers\/vosdroits\/F1292<\/a><\/span><\/p>\n<p><span style=\"color: #850a27;\"><strong>c) R\u00e9servistes des arm\u00e9es<\/strong><\/span><\/p>\n<p>Pour vous engager en tant que r\u00e9serviste op\u00e9rationnel du minist\u00e8re des Arm\u00e9es, veuillez consulter les informations ci-dessous puis d\u00e9poser votre candidature sur le site :<a href=\"https:\/\/www.reservistes.defense.gouv.fr\/\" target=\"_blank\" rel=\"noopener\"> <span style=\"color: #850a27;\">reservistes.defense.gouv.fr<\/span><\/a><\/p>\n<ol>\n<li><strong>d) La garde nationale<\/strong><\/li>\n<\/ol>\n<p>Le 13 octobre 2016, la garde nationale a \u00e9t\u00e9 officiellement cr\u00e9\u00e9e. C\u2019est un mod\u00e8le pragmatique, adoss\u00e9 \u00e0 une base existante et reposant sur deux piliers\u00a0: les r\u00e9serves op\u00e9rationnelles de premier niveau des Arm\u00e9es et formations rattach\u00e9es relevant du minist\u00e8re des Arm\u00e9es (pr\u00e9sent\u00e9es ci-dessous), ainsi que les r\u00e9serves op\u00e9rationnelles de premier niveau de la gendarmerie nationale ainsi que les r\u00e9serves civiles de la police nationale, relevant du minist\u00e8re de l\u2019Int\u00e9rieur. Pour plus d\u2019informations sur ces r\u00e9serves, rendez-vous sur le portail de la Garde nationale<strong> :<a href=\"\u00a0https:\/\/garde-nationale.gouv.fr\">\u00a0<\/a><\/strong><a href=\"\u00a0https:\/\/garde-nationale.gouv.fr\"><span style=\"color: #850a27;\">https:\/\/garde-nationale.gouv.fr<\/span><\/a><\/p>\n<p>Aucune condition de dipl\u00f4me n\u2019est exig\u00e9e pour int\u00e9grer la r\u00e9serve op\u00e9rationnelle des arm\u00e9es. L\u2019arm\u00e9e de terre, l\u2019arm\u00e9e de l\u2019air et la Marine nationale recrutent des personnes de sans dipl\u00f4me \u00e0 bac+5. Les directions et services du minist\u00e8re de la D\u00e9fense recherchent des personnes avec une qualification minimum.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-44b0807 elementor-widget elementor-widget-heading\" data-id=\"44b0807\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h3 class=\"elementor-heading-title elementor-size-default\">2) PARCOURS CITOYEN<\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-23feaf8 elementor-widget elementor-widget-text-editor\" data-id=\"23feaf8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p><strong>a) La journ\u00e9e D\u00e9fense et citoyennet\u00e9 (JDC) : <\/strong><span style=\"color: #850a27;\"><a style=\"color: #850a27;\" href=\"http:\/\/www.majdc.fr\/\">http:\/\/www.majdc.fr<\/a><\/span><\/p>\n<p><strong>Les trois \u00e9tapes du parcours. <\/strong>La sensibilisation de tous les jeunes aux enjeux de la d\u00e9fense et de la citoyennet\u00e9 repose depuis la loi de 1997 suspendant le service national, sur un parcours citoyen.<\/p>\n<p><strong>Il comporte trois \u00e9tapes obligatoires <\/strong>au cours desquelles interviennent successivement\u00a0: l\u2019\u00c9ducation nationale, les mairies et le Minist\u00e8re des Arm\u00e9es.<\/p>\n<ul>\n<li>L\u2019enseignement de d\u00e9fense \/ Education Nationale<\/li>\n<li>Le recensement \u00e0 16 ans \/ Mairie<\/li>\n<li>La Journ\u00e9e d\u00e9fense et citoyennet\u00e9 \/ Minist\u00e8re des arm\u00e9es<\/li>\n<\/ul>\n<p><strong>b) Centre d\u2019Information et de Recrutement des Forces Arm\u00e9es (CIRFA)<\/strong><\/p>\n<p>CIRFA de Chamb\u00e9ry:<br \/><span style=\"color: #850a27;\"><a style=\"color: #850a27;\" href=\"https:\/\/www.sengager.fr\/ou-nous-rencontrer\/cirfa-de-perigueux\" target=\"_blank\" rel=\"noopener\">https:\/\/www.sengager.fr\/ou-nous-rencontrer\/cirfa-de-chambery<\/a><\/span><\/p>\n<p>Arm\u00e9e de Terre :<br \/><span style=\"color: #850a27;\"><a style=\"color: #850a27;\" href=\"https:\/\/www.sengager.fr\/\">https:\/\/www.sengager.fr<\/a><\/span><\/p>\n<p>Arm\u00e9e de l\u2019Air et de l\u2019espace\u00a0:<br \/><span style=\"color: #850a27;\"><a style=\"color: #850a27;\" href=\"https:\/\/devenir-aviateur.fr\/\" target=\"_blank\" rel=\"noopener\">https:\/\/devenir-aviateur.fr<\/a><\/span><\/p>\n<p>Marine nationale\u00a0:<br \/><span style=\"color: #850a27;\"><a style=\"color: #850a27;\" href=\"https:\/\/www.etremarin.fr\/rejoignez-l-equipage\/se-renseigner\" target=\"_blank\" rel=\"noopener\">https:\/\/www.etremarin.fr\/rejoignez-l-equipage\/se-renseigner<\/a><\/span><\/p>\n<p>Gendarmerie nationale\u00a0:<br \/><span style=\"color: #850a27;\"><a style=\"color: #850a27;\" href=\"https:\/\/www.lagendarmerierecrute.fr\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.lagendarmerierecrute.fr<\/a><\/span><\/p>\n<p><span style=\"color: #850a27;\"><\/span><\/p>\n<p><span style=\"color: #850a27;\"><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-d0c9e4b elementor-widget elementor-widget-heading\" data-id=\"d0c9e4b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h3 class=\"elementor-heading-title elementor-size-default\">3) SOLIDARIT\u00c9 ET M\u00c9MOIRE<\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-0fffaca elementor-widget elementor-widget-text-editor\" data-id=\"0fffaca\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p><strong>L\u2019office national des anciens combattants et victimes de guerre. (ONACVG) :<\/strong><br \/><span style=\"color: #850a27;\"><a style=\"color: #850a27;\" href=\"https:\/\/www.onac-vg.fr\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.onac-vg.fr\/<\/a><\/span><\/p>\n<p>L\u2019Office national des anciens combattants et victimes de guerre est un \u00e9tablissement public sous tutelle du minist\u00e8re des Arm\u00e9es. Il accompagne depuis 1916 tous les combattants et les victimes des conflits.<\/p>\n<p>L\u2019ONACVG a trois missions principales : la reconnaissance et la r\u00e9paration, la solidarit\u00e9, et la m\u00e9moire.<br \/>Il a pour objectif de pr\u00e9server les int\u00e9r\u00eats mat\u00e9riels et moraux de ses ressortissants : anciens combattants, invalides et bless\u00e9s de guerre, veuves de guerre, pupilles de la Nation, victimes de guerre, et plus r\u00e9cemment, d\u2019actes de terrorisme.<br \/>Aujourd\u2019hui, il apporte un soutien \u00e0 pr\u00e8s de 3 millions de ressortissants de toutes les g\u00e9n\u00e9rations du feu.<br \/>Il est \u00e9galement l\u2019op\u00e9rateur majeur de la politique m\u00e9morielle du minist\u00e8re des Arm\u00e9es.<\/p>\n<p><strong>M\u00e9moire des hommes :<\/strong><br \/><span style=\"color: #850a27;\"><a style=\"color: #850a27;\" href=\"https:\/\/www.memoiredeshommes.sga.defense.gouv.fr\" target=\"_blank\" rel=\"noopener\">memoiredeshommes.sga.defense.gouv.fr<\/a><\/span><\/p>\n<p>Inaugur\u00e9 en novembre 2003, avec la seule base des Morts pour la France de la Premi\u00e8re Guerre mondiale au titre de m\u00e9morial virtuel en hommage aux combattants qui ont perdu la vie, le site M\u00e9moire des hommes est r\u00e9guli\u00e8rement enrichi par la suite. Il a vocation \u00e0 mettre \u00e0 la disposition du public des documents num\u00e9ris\u00e9s et des informations issues des fonds d\u2019archives conserv\u00e9es par le minist\u00e8re des arm\u00e9es. Il offre \u00e9galement un aper\u00e7u des tr\u00e8s riches collections de biens culturels dont le minist\u00e8re des arm\u00e9es est d\u00e9tenteur.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb90%\u00a0\u00bb width_tablet=\u00a0\u00bb\u00a0\u00bb width_phone=\u00a0\u00bb\u00a0\u00bb width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_padding=\u00a0\u00bb3px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner saved_specialty_column_type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\" align=\"justify\"><span>Contact : <a href=\"mailto:correspondant.defense.avressieux@free.fr\">correspondant.defense.avressieux@free.fr<\/a><\/span><\/p>\n<p style=\"text-align: center;\" align=\"justify\"><span>Page Facebook : <a href=\"https:\/\/www.facebook.com\/CORDEF73240\">https:\/\/www.facebook.com\/CORDEF73240<\/a><\/span><\/p>\n<p style=\"text-align: center;\" align=\"justify\"><span><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbTitre menu gauche\u00a0\u00bb _builder_version=\u00a0\u00bb4.6.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbOpen Sans|||||on|||\u00a0\u00bb text_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb background_color=\u00a0\u00bb#5a6792&Prime; custom_margin=\u00a0\u00bb-120px||0px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb custom_padding=\u00a0\u00bb60px|||15px|false|false\u00a0\u00bb global_module=\u00a0\u00bb2300&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.avressieux.com\/mairie\/wp-content\/uploads\/2020\/08\/puce1.png\" width=\"30\" height=\"30\" alt=\"puce\" class=\"wp-image-1266 alignleft size-full\" \/>Rubriques Vie communale<\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: 270px; top: 46.8px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00a0\u00bbMenu gauche\u00a0\u00bb _builder_version=\u00a0\u00bb4.6.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb text_font_size=\u00a0\u00bb14px\u00a0\u00bb link_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb background_color=\u00a0\u00bb#5a6792&Prime; custom_margin=\u00a0\u00bb0px||40px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb20px|20px|10px|20px|false|false\u00a0\u00bb link_letter_spacing_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_module=\u00a0\u00bb2302&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<ul>\n<li>Associations locales<br \/>&gt; <a href=\"https:\/\/www.avressieux.com\/mairie\/sou-des-ecoles-association\/\">Sou des \u00e9coles<br \/><\/a>&gt; <a href=\"https:\/\/www.avressieux.com\/mairie\/club-entente-et-amitie\/\">Club Entente et Amiti\u00e9<\/a><br \/>&gt; <a href=\"https:\/\/www.avressieux.com\/mairie\/comite-des-fetes-davressieux\/\">Comit\u00e9 des f\u00eates d&rsquo;Avressieux<\/a><br \/>&gt; <a href=\"https:\/\/www.avressieux.com\/mairie\/groupe-vocal-avressieux-chorale\/\">Groupe vocal \u00ab\u00a0Si l&rsquo;on chantait\u00a0\u00bb<\/a><br \/>&gt; <a href=\"https:\/\/www.avressieux.com\/mairie\/maison-des-jeunes-et-de-la-culture\/\">Maison des jeunes et de la culture<\/a><br \/>&gt; <a href=\"https:\/\/www.avressieux.com\/mairie\/association-communale-de-chasse\/\">Association communale de chasse<\/a><br \/>&gt; <a href=\"https:\/\/www.avressieux.com\/mairie\/association-des-familles\/\">Association des familles<\/a><br \/>&gt; <a href=\"https:\/\/www.avressieux.com\/mairie\/tireurs-de-montfleury\/\">Tireurs de Montfleury<\/a><br \/>&gt; <a href=\"https:\/\/www.avressieux.com\/mairie\/la-maison-de-la-ceramique\/\">La Maison de la c\u00e9ramique<\/a><\/li>\n<li><a href=\"https:\/\/www.avressieux.com\/mairie\/agenda-manifestations-a-venir-et-passees\/\">Agenda de la commune<\/a><\/li>\n<li><a href=\"http:\/\/www.belmont-tramonet.fr\/www-rubrique-26-fr-BT.html\" target=\"_blank\" rel=\"noopener noreferrer\">Biblioth\u00e8que \u00ab\u00a0Montbel Auteurs\u00a0\u00bb<\/a><\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_divider color=\u00a0\u00bb#ffffff\u00a0\u00bb divider_weight=\u00a0\u00bb12px\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][et_pb_sidebar orientation=\u00a0\u00bbright\u00a0\u00bb area=\u00a0\u00bbet_pb_widget_area_4&Prime; show_border=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.6.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb body_font_size=\u00a0\u00bb13px\u00a0\u00bb custom_padding=\u00a0\u00bb|10px||10px|false|false\u00a0\u00bb global_module=\u00a0\u00bb1957&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_sidebar][\/et_pb_column][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>le correspondant d\u00e9fense Le Correspondant D\u00e9fense est l\u2019interlocuteur privil\u00e9gi\u00e9 des citoyens sur les questions de D\u00e9fense au sein de la commune. Cr\u00e9\u00e9e en 2001, par le minist\u00e8re d\u00e9l\u00e9gu\u00e9 aux Anciens combattants, la fonction de correspondant d\u00e9fense a vocation \u00e0 d\u00e9velopper le lien arm\u00e9e-nation et promouvoir l\u2019esprit de d\u00e9fense. Le r\u00f4le du correspondant d\u00e9fense est essentiel [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:paragraph -->\n<p>Ceci est une page d\u2019exemple. C\u2019est diff\u00e9rent d\u2019un article de blog parce qu\u2019elle restera au m\u00eame endroit et appara\u00eetra dans la navigation de votre site (dans la plupart des th\u00e8mes). La plupart des gens commencent par une page \u00ab&nbsp;\u00c0 propos&nbsp;\u00bb qui les pr\u00e9sente aux visiteurs du site. Cela pourrait ressembler \u00e0 quelque chose comme cela&nbsp;:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><p>Bonjour&nbsp;! Je suis un m\u00e9canicien qui aspire \u00e0 devenir acteur, et voici mon site. J\u2019habite \u00e0 Bordeaux, j\u2019ai un super chien baptis\u00e9 Russell, et j\u2019aime la vodka-ananas (ainsi qu\u2019\u00eatre surpris par la pluie soudaine lors de longues balades sur la plage au coucher du soleil).<\/p><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>... ou quelque chose comme cela&nbsp;:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><p>La soci\u00e9t\u00e9 123 Machin Truc a \u00e9t\u00e9 cr\u00e9\u00e9e en 1971, et n\u2019a cess\u00e9 de proposer au public des machins-trucs de qualit\u00e9 depuis lors. Situ\u00e9e \u00e0 Saint-Remy-en-Bouzemont-Saint-Genest-et-Isson, 123 Machin Truc emploie 2 000 personnes, et fabrique toutes sortes de bidules super pour la communaut\u00e9 bouzemontoise.<\/p><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>En tant que nouvel\u00b7le utilisateur ou utilisatrice de WordPress, vous devriez vous rendre sur <a href=\"http:\/\/www.avressieux.com\/mairie\/wp-admin\/\">votre tableau de bord<\/a> pour supprimer cette page et cr\u00e9er de nouvelles pages pour votre contenu. Amusez-vous bien&nbsp;!<\/p>\n<!-- \/wp:paragraph -->","_et_gb_content_width":"","footnotes":""},"class_list":["post-3434","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Correspondant D\u00e9fense | Association des seniors | 73240 Avressieux<\/title>\n<meta name=\"description\" content=\"Le Correspondant D\u00e9fense | Commune d&#039;Avressieux, 73240 | Animations, \u00e9v\u00e9nements, sorties, manifestations \u00e0 venir\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.avressieux.com\/mairie\/le-correspondant-defense\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Correspondant D\u00e9fense | Association des seniors | 73240 Avressieux\" \/>\n<meta property=\"og:description\" content=\"Le Correspondant D\u00e9fense | Commune d&#039;Avressieux, 73240 | Animations, \u00e9v\u00e9nements, sorties, manifestations \u00e0 venir\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.avressieux.com\/mairie\/le-correspondant-defense\/\" \/>\n<meta property=\"og:site_name\" content=\"Avressieux\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Mairie-dAvressieux-104859844654359\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-26T14:00:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.avressieux.com\/mairie\/wp-content\/uploads\/2020\/08\/puce1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/le-correspondant-defense\\\/\",\"url\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/le-correspondant-defense\\\/\",\"name\":\"Le Correspondant D\u00e9fense | Association des seniors | 73240 Avressieux\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/le-correspondant-defense\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/le-correspondant-defense\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/puce1.png\",\"datePublished\":\"2022-10-26T14:00:40+00:00\",\"dateModified\":\"2022-10-26T14:00:53+00:00\",\"description\":\"Le Correspondant D\u00e9fense | Commune d'Avressieux, 73240 | Animations, \u00e9v\u00e9nements, sorties, manifestations \u00e0 venir\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/le-correspondant-defense\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/le-correspondant-defense\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/le-correspondant-defense\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/puce1.png\",\"contentUrl\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/puce1.png\",\"width\":30,\"height\":30,\"caption\":\"puce\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/le-correspondant-defense\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Correspondant D\u00e9fense\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/#website\",\"url\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/\",\"name\":\"Avressieux\",\"description\":\"Site officiel de la commune\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/#organization\",\"name\":\"Commune d'Avressieux\",\"url\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/favicon.jpg\",\"width\":512,\"height\":512,\"caption\":\"Commune d'Avressieux\"},\"image\":{\"@id\":\"https:\\\/\\\/www.avressieux.com\\\/mairie\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Mairie-dAvressieux-104859844654359\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Correspondant D\u00e9fense | Association des seniors | 73240 Avressieux","description":"Le Correspondant D\u00e9fense | Commune d'Avressieux, 73240 | Animations, \u00e9v\u00e9nements, sorties, manifestations \u00e0 venir","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.avressieux.com\/mairie\/le-correspondant-defense\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Correspondant D\u00e9fense | Association des seniors | 73240 Avressieux","og_description":"Le Correspondant D\u00e9fense | Commune d'Avressieux, 73240 | Animations, \u00e9v\u00e9nements, sorties, manifestations \u00e0 venir","og_url":"https:\/\/www.avressieux.com\/mairie\/le-correspondant-defense\/","og_site_name":"Avressieux","article_publisher":"https:\/\/www.facebook.com\/Mairie-dAvressieux-104859844654359\/","article_modified_time":"2022-10-26T14:00:53+00:00","og_image":[{"url":"https:\/\/www.avressieux.com\/mairie\/wp-content\/uploads\/2020\/08\/puce1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.avressieux.com\/mairie\/le-correspondant-defense\/","url":"https:\/\/www.avressieux.com\/mairie\/le-correspondant-defense\/","name":"Le Correspondant D\u00e9fense | Association des seniors | 73240 Avressieux","isPartOf":{"@id":"https:\/\/www.avressieux.com\/mairie\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.avressieux.com\/mairie\/le-correspondant-defense\/#primaryimage"},"image":{"@id":"https:\/\/www.avressieux.com\/mairie\/le-correspondant-defense\/#primaryimage"},"thumbnailUrl":"https:\/\/www.avressieux.com\/mairie\/wp-content\/uploads\/2020\/08\/puce1.png","datePublished":"2022-10-26T14:00:40+00:00","dateModified":"2022-10-26T14:00:53+00:00","description":"Le Correspondant D\u00e9fense | Commune d'Avressieux, 73240 | Animations, \u00e9v\u00e9nements, sorties, manifestations \u00e0 venir","breadcrumb":{"@id":"https:\/\/www.avressieux.com\/mairie\/le-correspondant-defense\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.avressieux.com\/mairie\/le-correspondant-defense\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.avressieux.com\/mairie\/le-correspondant-defense\/#primaryimage","url":"https:\/\/www.avressieux.com\/mairie\/wp-content\/uploads\/2020\/08\/puce1.png","contentUrl":"https:\/\/www.avressieux.com\/mairie\/wp-content\/uploads\/2020\/08\/puce1.png","width":30,"height":30,"caption":"puce"},{"@type":"BreadcrumbList","@id":"https:\/\/www.avressieux.com\/mairie\/le-correspondant-defense\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.avressieux.com\/mairie\/"},{"@type":"ListItem","position":2,"name":"Le Correspondant D\u00e9fense"}]},{"@type":"WebSite","@id":"https:\/\/www.avressieux.com\/mairie\/#website","url":"https:\/\/www.avressieux.com\/mairie\/","name":"Avressieux","description":"Site officiel de la commune","publisher":{"@id":"https:\/\/www.avressieux.com\/mairie\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.avressieux.com\/mairie\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.avressieux.com\/mairie\/#organization","name":"Commune d'Avressieux","url":"https:\/\/www.avressieux.com\/mairie\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.avressieux.com\/mairie\/#\/schema\/logo\/image\/","url":"https:\/\/www.avressieux.com\/mairie\/wp-content\/uploads\/2020\/08\/favicon.jpg","contentUrl":"https:\/\/www.avressieux.com\/mairie\/wp-content\/uploads\/2020\/08\/favicon.jpg","width":512,"height":512,"caption":"Commune d'Avressieux"},"image":{"@id":"https:\/\/www.avressieux.com\/mairie\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Mairie-dAvressieux-104859844654359\/"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 12:40:56","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.avressieux.com\/mairie\/wp-json\/wp\/v2\/pages\/3434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.avressieux.com\/mairie\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.avressieux.com\/mairie\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.avressieux.com\/mairie\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.avressieux.com\/mairie\/wp-json\/wp\/v2\/comments?post=3434"}],"version-history":[{"count":3,"href":"https:\/\/www.avressieux.com\/mairie\/wp-json\/wp\/v2\/pages\/3434\/revisions"}],"predecessor-version":[{"id":3897,"href":"https:\/\/www.avressieux.com\/mairie\/wp-json\/wp\/v2\/pages\/3434\/revisions\/3897"}],"wp:attachment":[{"href":"https:\/\/www.avressieux.com\/mairie\/wp-json\/wp\/v2\/media?parent=3434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}